{"id":39132,"date":"2024-07-09T18:42:30","date_gmt":"2024-07-09T14:12:30","guid":{"rendered":"https:\/\/ijmarket.com\/blog\/?p=39132"},"modified":"2025-10-14T04:35:25","modified_gmt":"2025-10-14T01:05:25","slug":"%d8%a7%db%8c%d8%a7-%d9%85%db%8c%d8%b4%d9%88%d8%af-%d9%81%db%8c%d8%b3%d8%aa%d9%88%d9%84-%d8%b1%d8%a7-%d8%b9%d9%85%d9%84-%d9%86%da%a9%d8%b1%d8%af-%d9%88-%d8%a8%d9%87-%d8%ae%d9%88%d8%af%db%8c-%d8%ae","status":"publish","type":"post","link":"https:\/\/ijmarket.com\/blog\/%d8%a7%db%8c%d8%a7-%d9%85%db%8c%d8%b4%d9%88%d8%af-%d9%81%db%8c%d8%b3%d8%aa%d9%88%d9%84-%d8%b1%d8%a7-%d8%b9%d9%85%d9%84-%d9%86%da%a9%d8%b1%d8%af-%d9%88-%d8%a8%d9%87-%d8%ae%d9%88%d8%af%db%8c-%d8%ae\/","title":{"rendered":"\u0627\u06cc\u0627 \u0645\u06cc\u0634\u0648\u062f \u0641\u06cc\u0633\u062a\u0648\u0644 \u0631\u0627 \u0639\u0645\u0644 \u0646\u06a9\u0631\u062f \u0648 \u0628\u0647 \u062e\u0648\u062f\u06cc \u062e\u0648\u062f \u062e\u0648\u0628 \u0645\u06cc\u0634\u0648\u062f\u061f"},"content":{"rendered":"<p style=\"text-align: center;\">\n<p style=\"text-align: justify;\">\u0627\u063a\u0644\u0628 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0641\u06cc\u0633\u062a\u0648\u0644\u060c \u0639\u0645\u0644 \u062c\u0631\u0627\u062d\u06cc \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u0627\u0633\u062a \u0632\u06cc\u0631\u0627 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0628\u0647 \u062e\u0648\u062f\u06cc \u062e\u0648\u062f \u0628\u0647\u0628\u0648\u062f \u0646\u0645\u06cc \u06cc\u0627\u0628\u062f. \u0686\u0646\u062f\u06cc\u0646 \u0631\u0648\u0634 \u062f\u0631\u0645\u0627\u0646 \u0645\u062e\u062a\u0644\u0641 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f. \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0628\u0633\u062a\u06af\u06cc \u0628\u0647 \u0645\u0648\u0642\u0639\u06cc\u062a \u0648 \u0634\u062f\u062a \u0641\u06cc\u0633\u062a\u0648\u0644 \u062f\u0627\u0631\u062f \u0648 \u0627\u06cc\u0646\u06a9\u0647 \u0622\u06cc\u0627 \u0627\u06cc\u0646 \u0641\u06cc\u0633\u062a\u0648\u0644 \u06cc\u06a9 \u06a9\u0627\u0646\u0627\u0644 \u0627\u0633\u062a \u06cc\u0627 \u062f\u0631 \u062c\u0647\u0627\u062a \u0645\u062e\u062a\u0644\u0641 \u0645\u0646\u0634\u0639\u0628 \u0645\u06cc \u0634\u0648\u062f.<\/p>\n<h2 style=\"text-align: justify;\">\u0627\u06cc\u0627 \u0645\u06cc\u0634\u0648\u062f \u0641\u06cc\u0633\u062a\u0648\u0644 \u0631\u0627 \u0639\u0645\u0644 \u0646\u06a9\u0631\u062f<\/h2>\n<p style=\"text-align: justify;\">\u0627\u06af\u0631 \u0641\u06cc\u0633\u062a\u0648\u0644 \u0628\u0647 \u0645\u0648\u0642\u0639 \u062f\u0631\u0645\u0627\u0646 \u0646\u0634\u0648\u062f\u060c \u0627\u063a\u0644\u0628 \u062e\u0637\u0631 \u067e\u06cc\u0634\u0631\u0641\u062a \u0634\u062f\u06cc\u062f \u0631\u0627 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0631\u062f \u0648 \u0639\u0648\u0627\u0631\u0636 \u0648 \u0645\u0634\u06a9\u0644\u0627\u062a \u0632\u06cc\u0627\u062f\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc \u06a9\u0646\u062f. \u062f\u0631 \u0645\u0648\u0631\u062f \u0627\u06cc\u0646\u06a9\u0647 \u0627\u06cc\u0627 \u0641\u06cc\u0633\u062a\u0648\u0644 \u0628\u0647 \u062e\u0648\u062f\u06cc \u062e\u0648\u062f \u062e\u0648\u0628 \u0645\u06cc\u0634\u0648\u062f \u06cc\u0627 \u0646\u0647\u060c \u0628\u0647 \u06af\u0641\u062a\u0647 \u0645\u062a\u062e\u0635\u0635\u0627\u0646\u060c \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u062e\u0648\u062f\u06cc \u062e\u0648\u062f \u0642\u0627\u0628\u0644 \u062f\u0631\u0645\u0627\u0646 \u0646\u06cc\u0633\u062a \u0648 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u062f\u0631\u0645\u0627\u0646 \u0641\u0648\u0631\u06cc \u062f\u0627\u0631\u062f.<br \/>\u0639\u0641\u0648\u0646\u062a\u060c \u062a\u0631\u0634\u062d \u0686\u0631\u06a9 \u062f\u0631 \u0646\u0627\u062d\u06cc\u0647 \u0645\u0642\u0639\u062f \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062a\u0639\u062f\u0627\u062f \u0641\u06cc\u0633\u062a\u0648\u0644 \u0647\u0627\u060c \u062f\u0631\u0645\u0627\u0646 \u0631\u0627 \u062f\u0634\u0648\u0627\u0631\u062a\u0631 \u0645\u06cc \u06a9\u0646\u062f. \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0627\u0644\u062a\u0647\u0627\u0628 \u0645\u0642\u0639\u062f \u0628\u0631\u0627\u06cc \u0645\u062f\u062a \u0637\u0648\u0644\u0627\u0646\u06cc \u0627\u062f\u0627\u0645\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f\u060c \u062e\u0637\u0631 \u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u0633\u0631\u0637\u0627\u0646 \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc \u062f\u0647\u062f. \u0628\u0631\u0627\u06cc \u0628\u06cc\u0645\u0627\u0631\u0627\u0646 \u0645\u0628\u062a\u0644\u0627 \u0628\u0647 \u0622\u0628\u0633\u0647 \u0645\u0642\u0639\u062f\u060c \u062c\u0631\u0627\u062d\u06cc \u0628\u0631\u0627\u06cc \u0627\u06cc\u062c\u0627\u062f \u0628\u0631\u0634 \u0628\u0631\u0627\u06cc \u062a\u062e\u0644\u06cc\u0647 \u0686\u0631\u06a9 \u0628\u0627\u06cc\u062f \u062f\u0631 \u0627\u0633\u0631\u0639 \u0648\u0642\u062a \u0627\u0646\u062c\u0627\u0645 \u0634\u0648\u062f \u062a\u0627 \u0627\u0632 \u0633\u0631\u0631\u06cc\u0632 \u0686\u0631\u06a9 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0634\u0648\u062f. \u0627\u06cc\u0646 \u0627\u0645\u0631 \u0645\u0646\u062c\u0631 \u0628\u0647 \u062a\u0634\u06a9\u06cc\u0644 \u062a\u0648\u0646\u0644 \u0647\u0627\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0645\u0627\u0646\u0646\u062f \u0631\u06af\u0647 \u0647\u0627\u06cc \u0645\u0627\u0631\u0645\u0627\u0647\u06cc \u062f\u0631 \u0646\u0627\u062d\u06cc\u0647 \u0645\u0642\u0639\u062f \u0645\u06cc \u0634\u0648\u062f \u06a9\u0647 \u0628\u0647 \u0646\u0648\u0628\u0647 \u062e\u0648\u062f \u0628\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u0646\u062f\u0627\u0645 \u0647\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u062d\u0644 \u0622\u0633\u06cc\u0628 \u0645\u06cc \u0631\u0633\u0627\u0646\u062f.<\/p>\n<h2 style=\"text-align: justify;\">\u0631\u0627\u0647 \u062d\u0644 \u06a9\u0627\u0645\u0644\u0627 \u0645\u0648\u062b\u0631 \u0648 \u0642\u0637\u0639\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0641\u06cc\u0633\u062a\u0648\u0644 \u0645\u0642\u0639\u062f\u06cc \u0686\u06cc\u0633\u062a\u061f<\/h2>\n<p style=\"text-align: justify;\">\u0641\u06cc\u0633\u062a\u0648\u0644 \u0645\u0642\u0639\u062f\u06cc \u0628\u06cc\u0645\u0627\u0631\u06cc \u0627\u06cc \u0646\u06cc\u0633\u062a \u06a9\u0647 \u062e\u0648\u062f\u0634 \u062e\u0648\u062f \u0628\u0647 \u062e\u0648\u062f \u062e\u0648\u0628 \u0634\u0648\u062f \u0648 \u0627\u06af\u0631 \u0628\u0647 \u0645\u0648\u0642\u0639 \u062f\u0631\u0645\u0627\u0646 \u0646\u0634\u0648\u062f \u0631\u0648\u0646\u062f \u0628\u0647\u0628\u0648\u062f\u06cc \u067e\u06cc\u0686\u06cc\u062f\u0647 \u062a\u0631 \u0648 \u0633\u062e\u062a \u062a\u0631 \u062e\u0648\u0627\u0647\u062f \u0634\u062f.<br \/>\u0628\u0647 \u06af\u0641\u062a\u0647 \u0645\u062a\u062e\u0635\u0635\u0627\u0646\u060c \u0645\u062a\u062f\u0627\u0648\u0644 \u062a\u0631\u06cc\u0646 \u0648 \u0645\u0648\u062b\u0631\u062a\u0631\u06cc\u0646 \u0631\u0648\u0634 \u062f\u0631\u0645\u0627\u0646 \u0641\u06cc\u0633\u062a\u0648\u0644 \u0645\u0642\u0639\u062f\u06cc \u062f\u0631 \u062d\u0627\u0644 \u062d\u0627\u0636\u0631 \u062c\u0631\u0627\u062d\u06cc \u0627\u0633\u062a.<\/p>\n<p style=\"text-align: justify;\">\u062f\u0631 \u0631\u0648\u0634 \u0639\u0645\u0644 \u062c\u0631\u0627\u062d\u06cc \u0641\u06cc\u0633\u062a\u0648\u0644 \u067e\u0632\u0634\u06a9 \u0641\u06cc\u0633\u062a\u0648\u0644 \u0631\u0627 \u0628\u0631\u06cc\u062f\u0647 \u06cc\u0627 \u0628\u0631\u0634 \u0645\u06cc \u062f\u0647\u062f \u062a\u0627 \u0641\u06cc\u0633\u062a\u0648\u0644 \u0639\u0641\u0648\u0646\u06cc \u0628\u0627\u0632 \u0634\u0648\u062f. \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0628\u0647\u0628\u0648\u062f \u0632\u062e\u0645 \u0631\u0627 \u0627\u0632 \u062f\u0627\u062e\u0644 \u0628\u0647 \u0628\u06cc\u0631\u0648\u0646 \u062a\u0633\u0647\u06cc\u0644 \u0645\u06cc \u06a9\u0646\u062f \u0648 \u0627\u0632 \u0627\u06cc\u062c\u0627\u062f \u062a\u0648\u062f\u0647 \u0647\u0627\u06cc \u0686\u0631\u06a9\u06cc \u062f\u0631 \u062f\u0627\u062e\u0644 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0645\u06cc \u06a9\u0646\u062f.<br \/>\u062f\u0631 \u0645\u0648\u0631\u062f <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/clinicdarman.com\/%D8%AF%D8%A7%D9%86%D8%B3%D8%AA%D9%86%DB%8C%D9%87%D8%A7%DB%8C-%D8%B3%D8%A7%DB%8C%D8%AA\/%D8%B9%D9%85%D9%84-%D8%AC%D8%B1%D8%A7%D8%AD%DB%8C-%D9%81%DB%8C%D8%B3%D8%AA%D9%88%D9%84\/\">\u062f\u0648\u0631\u0627\u0646 \u0646\u0642\u0627\u0647\u062a \u0628\u0639\u062f \u0627\u0632 \u0639\u0645\u0644 \u0641\u06cc\u0633\u062a\u0648\u0644<\/a> \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646\u06a9\u0647 \u0628\u06cc\u0645\u0627\u0631 \u0628\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0633\u0631\u0639\u062a \u067e\u0633 \u0627\u0632 \u062c\u0631\u0627\u062d\u06cc \u0641\u06cc\u0633\u062a\u0648\u0644 \u0645\u0642\u0639\u062f\u06cc \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0627\u0645\u0644 \u0628\u0647\u0628\u0648\u062f \u06cc\u0627\u0628\u062f\u060c \u0628\u0627\u06cc\u062f \u0628\u0647 \u0645\u0648\u0627\u0631\u062f \u0632\u06cc\u0631 \u062a\u0648\u062c\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f:<\/p>\n<p style=\"text-align: center;\">\n<ul style=\"text-align: justify;\">\n<li style=\"list-style-type: none;\">\n<ul>\n<li>\u062d\u062f\u0648\u062f \u062f\u0648 \u062a\u0627 \u0633\u0647 \u0631\u0648\u0632 \u062f\u0631 \u0628\u06cc\u0645\u0627\u0631\u0633\u062a\u0627\u0646 \u0627\u0633\u062a\u0631\u0627\u062d\u062a \u06a9\u0646\u062f \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u062e\u0627\u0646\u0647 \u0628\u0631\u0648\u062f.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>\u062a\u0648\u062c\u0647 \u0628\u0647 \u0631\u0698\u06cc\u0645 \u063a\u0630\u0627\u06cc\u06cc \u0631\u0648\u0632\u0627\u0646\u0647 : \u0645\u0635\u0631\u0641 \u063a\u0630\u0627\u0647\u0627\u06cc \u063a\u0646\u06cc \u0627\u0632 \u0641\u06cc\u0628\u0631\u060c \u0648\u06cc\u062a\u0627\u0645\u06cc\u0646 \u0647\u0627\u060c \u063a\u0630\u0627\u0647\u0627\u06cc \u0645\u0644\u06cc\u0646 \u06a9\u0647 \u0628\u0647 \u0633\u06cc\u0633\u062a\u0645 \u06af\u0648\u0627\u0631\u0634 \u06a9\u0645\u06a9 \u0645\u06cc \u06a9\u0646\u062f \u0628\u0631\u0627\u06cc \u067e\u06cc\u0634\u06af\u06cc\u0631\u06cc \u0627\u0632 \u06cc\u0628\u0648\u0633\u062a.<\/li>\n<li>\u0633\u0639\u06cc \u06a9\u0646\u06cc\u062f \u0622\u0628 \u0648 \u0622\u0628\u0645\u06cc\u0648\u0647 \u0632\u06cc\u0627\u062f\u06cc \u0628\u0646\u0648\u0634\u06cc\u062f.<\/li>\n<li>\u0645\u0635\u0631\u0641 \u063a\u0630\u0627\u0647\u0627\u06cc \u0686\u0631\u0628 \u0648 \u062a\u0646\u062f \u0648 \u063a\u0630\u0627\u0647\u0627\u06cc \u0645\u062d\u0631\u06a9 \u0631\u0627 \u0645\u062d\u062f\u0648\u062f \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0628\u0647 \u0633\u06cc\u0633\u062a\u0645 \u06af\u0648\u0627\u0631\u0634\u06cc \u0622\u0633\u06cc\u0628 \u0646\u0631\u0633\u0627\u0646\u06cc\u062f.<\/li>\n<li>\u0627\u0632 \u0646\u0634\u0633\u062a\u0646 \u06cc\u0627 \u062f\u0631\u0627\u0632 \u06a9\u0634\u06cc\u062f\u0646 \u0637\u0648\u0644\u0627\u0646\u06cc \u0645\u062f\u062a \u062f\u0631 \u06cc\u06a9 \u0645\u06a9\u0627\u0646 \u062e\u0648\u062f\u062f\u0627\u0631\u06cc \u06a9\u0646\u06cc\u062f \u0648 \u062a\u0645\u0631\u06cc\u0646\u0627\u062a \u0648\u0631\u0632\u0634\u06cc \u0645\u0644\u0627\u06cc\u0645 \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u06cc\u062f.<\/li>\n<li>\u067e\u0633 \u0627\u0632 \u062c\u0631\u0627\u062d\u06cc\u060c \u062a\u0645\u06cc\u0632 \u0646\u06af\u0647 \u062f\u0627\u0634\u062a\u0646 \u0645\u0642\u0639\u062f \u0648 \u0634\u0633\u062a\u0634\u0648\u06cc \u0645\u0642\u0639\u062f \u0628\u0627 \u0622\u0628 \u06af\u0631\u0645\u060c \u0628\u0647 \u062e\u0635\u0648\u0635 \u0628\u0639\u062f \u0627\u0632 \u0627\u062c\u0627\u0628\u062a \u0645\u0632\u0627\u062c\u060c \u0627\u0647\u0645\u06cc\u062a \u0628\u0627\u0644\u0627\u06cc\u06cc \u062f\u0627\u0631\u062f.<\/li>\n<li>\u0628\u0639\u062f \u0627\u0632 \u0639\u0645\u0644 \u0628\u0647 \u0645\u0648\u0642\u0639 \u0645\u0639\u0627\u06cc\u0646\u0627\u062a \u0645\u0646\u0638\u0645 \u0637\u0628\u0642 \u062a\u0648\u0635\u06cc\u0647 \u067e\u0632\u0634\u06a9 \u0631\u0627 \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u06cc\u062f.<\/li>\n<li>\u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u0628\u0631\u0627\u06cc \u06a9\u0627\u0647\u0634 \u0646\u0627\u0631\u0627\u062d\u062a\u06cc \u062f\u0631 \u062f\u0648\u0631\u0647 \u067e\u0633 \u0627\u0632 \u0639\u0645\u0644\u060c \u062f\u0627\u0631\u0648\u0647\u0627\u06cc \u0645\u0633\u06a9\u0646 \u0627\u0636\u0627\u0641\u06cc \u0646\u06cc\u0632 \u0628\u0631\u0627\u06cc \u0628\u06cc\u0645\u0627\u0631 \u062a\u062c\u0648\u06cc\u0632 \u062e\u0648\u0627\u0647\u062f \u0634\u062f.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\u0641\u06cc\u0633\u062a\u0648\u0644 \u0647\u0627\u06cc \u0633\u0627\u062f\u0647 \u0647\u06cc\u0686 \u0634\u0627\u062e\u0647 \u0627\u06cc \u0627\u0632 \u062f\u0633\u062a\u06af\u0627\u0647 \u0627\u0648\u0644\u06cc\u0647 \u0646\u062f\u0627\u0631\u0646\u062f. \u0631\u0648\u0634\u06cc \u0628\u0647 \u0646\u0627\u0645 \u0641\u06cc\u0633\u062a\u0648\u0644\u0648\u062a\u0648\u0645\u06cc \u062d\u062f\u0627\u0642\u0644 \u0645\u0642\u062f\u0627\u0631 \u0628\u0627\u0641\u062a\u06cc \u0631\u0627 \u0628\u0631\u062f\u0627\u0634\u062a\u0647 \u0648 \u0628\u0647 \u0641\u06cc\u0633\u062a\u0648\u0644 \u0627\u062c\u0627\u0632\u0647 \u0645\u06cc \u062f\u0647\u062f \u062a\u0627 \u0628\u0647\u0628\u0648\u062f \u06cc\u0627\u0628\u062f. \u0627\u06cc\u0646 \u06cc\u06a9 \u0631\u0627\u0647 \u0645\u0648\u062b\u0631 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0641\u06cc\u0633\u062a\u0648\u0644 \u0647\u0627\u06cc \u0633\u0627\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<p style=\"text-align: justify;\">\u0641\u06cc\u0633\u062a\u0648\u0644 \u0647\u0627\u06cc \u067e\u06cc\u0686\u06cc\u062f\u0647 \u0639\u0636\u0644\u0647 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0631\u0627 \u062f\u0631\u06af\u06cc\u0631 \u0645\u06cc \u06a9\u0646\u0646\u062f \u0648 \u0645\u062c\u0631\u0627\u06cc \u0641\u06cc\u0633\u062a\u0648\u0644 \u0627\u0648\u0644\u06cc\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0634\u0627\u062e\u0647 \u0647\u0627\u06cc \u0632\u06cc\u0627\u062f\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f. \u0627\u0632 \u0622\u0646\u062c\u0627\u06cc\u06cc \u06a9\u0647 \u0628\u0631\u0634 \u06af\u0633\u062a\u0631\u062f\u0647 \u0628\u0627\u0641\u062a \u0639\u0636\u0644\u0627\u0646\u06cc \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u06a9\u0646\u062a\u0631\u0644 \u0631\u0648\u062f\u0647 \u0631\u0627 \u0628\u0647 \u062e\u0637\u0631 \u0628\u06cc\u0646\u062f\u0627\u0632\u062f\u060c \u0641\u06cc\u0633\u062a\u0648\u0644\u0648\u062a\u0648\u0645\u06cc \u0628\u0647\u062a\u0631\u06cc\u0646 \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0631\u0627\u06cc \u0641\u06cc\u0633\u062a\u0648\u0644 \u0647\u0627\u06cc \u067e\u06cc\u0686\u06cc\u062f\u0647 \u0646\u06cc\u0633\u062a.<\/p>\n<p style=\"text-align: justify;\">\u06cc\u06a9 \u0631\u0648\u06cc\u06a9\u0631\u062f \u0631\u0627\u06cc\u062c \u0628\u0631\u0627\u06cc \u0641\u06cc\u0633\u062a\u0648\u0644\u202f\u0647\u0627\u06cc \u0645\u0642\u0639\u062f\u06cc \u067e\u06cc\u0686\u06cc\u062f\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0646\u062e \u0633\u062a\u0648\u0646\u060c \u0646\u0648\u0639\u06cc \u0646\u062e \u062c\u0631\u0627\u062d\u06cc \u06a9\u0647 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0641\u06cc\u0633\u062a\u0648\u0644 \u062d\u0644\u0642\u0647 \u0645\u06cc\u202f\u0634\u0648\u062f \u062a\u0627 \u0632\u0647\u06a9\u0634\u06cc \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0647\u062f\u060c \u0645\u06cc \u0628\u0627\u0634\u062f. \u0627\u06af\u0631 \u062a\u062e\u0644\u06cc\u0647 \u0633\u062a\u0648\u0646 \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0646\u0628\u0627\u0634\u062f\u060c \u0633\u0627\u06cc\u0631 \u062a\u06a9\u0646\u06cc\u06a9 \u0647\u0627\u06cc \u062c\u0631\u0627\u062d\u06cc \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0647\u0633\u062a\u0646\u062f.<\/p>\n<h2 style=\"text-align: justify;\">\u0627\u06cc\u0627 \u0641\u06cc\u0633\u062a\u0648\u0644 \u0628\u0647 \u062e\u0648\u062f\u06cc \u062e\u0648\u062f \u062e\u0648\u0628 \u0645\u06cc\u0634\u0648\u062f<\/h2>\n<blockquote class=\"quote-light\">\n<p>\u0645\u0634\u0627\u0647\u062f\u0647 \u0645\u06cc \u0634\u0648\u062f \u06a9\u0647 \u062c\u0631\u0627\u062d\u06cc \u062a\u0646\u0647\u0627 \u0631\u0627\u0647 \u062f\u0631\u0645\u0627\u0646 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0627\u0633\u062a.\u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0633\u0627\u06cc\u062a coloradocolonandrectalspecialists<\/p>\n<p dir=\"ltr\">While it\u2019s possible, in theory, for an anal fistula to heal spontaneously, this usually doesn\u2019t happen. Most fistulas in this region start in anal glands that do become infected. Even if a fistula begins to heal, chances are very high that abscesses and infections will happen again.<\/p>\n<p>\u062a\u0631\u062c\u0645\u0647 \u0641\u0627\u0631\u0633\u06cc: \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0627\u0632 \u0646\u0638\u0631 \u062a\u0626\u0648\u0631\u06cc \u0627\u0645\u06a9\u0627\u0646 \u0628\u0647\u0628\u0648\u062f \u062e\u0648\u062f \u0628\u0647 \u062e\u0648\u062f \u0641\u06cc\u0633\u062a\u0648\u0644 \u0645\u0642\u0639\u062f\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f\u060c \u0627\u0645\u0627 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0627\u06cc\u0646 \u0627\u062a\u0641\u0627\u0642 \u0646\u0645\u06cc \u0627\u0641\u062a\u062f. \u0628\u06cc\u0634\u062a\u0631 \u0641\u06cc\u0633\u062a\u0648\u0644 \u0647\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0646\u0627\u062d\u06cc\u0647 \u0627\u0632 \u063a\u062f\u062f \u0645\u0642\u0639\u062f\u06cc \u0634\u0631\u0648\u0639 \u0645\u06cc \u0634\u0648\u0646\u062f \u06a9\u0647 \u0639\u0641\u0648\u0646\u06cc \u0645\u06cc \u0634\u0648\u0646\u062f. \u062d\u062a\u06cc \u0627\u06af\u0631 \u0641\u06cc\u0633\u062a\u0648\u0644 \u0634\u0631\u0648\u0639 \u0628\u0647 \u0628\u0647\u0628\u0648\u062f\u06cc \u06a9\u0646\u062f\u060c \u0627\u062d\u062a\u0645\u0627\u0644 \u0648\u0642\u0648\u0639 \u0645\u062c\u062f\u062f \u0622\u0628\u0633\u0647 \u0648 \u0639\u0641\u0648\u0646\u062a \u0628\u0633\u06cc\u0627\u0631 \u0632\u06cc\u0627\u062f \u0627\u0633\u062a.<\/p>\n<p>coloradocolonandrectalspecialists.com\/blog\/can-an-anal-fistula-heal-on-its-own<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">\u0641\u06cc\u0633\u062a\u0648\u0644 \u062f\u0631 \u062d\u062f\u0648\u062f 50 \u062f\u0631\u0635\u062f \u0627\u0632 \u0645\u0648\u0627\u0642\u0639 \u067e\u0633 \u0627\u0632 \u0639\u0641\u0648\u0646\u06cc \u0634\u062f\u0646 \u063a\u062f\u0647 \u0645\u0642\u0639\u062f\u06cc \u0631\u062e \u0645\u06cc \u062f\u0647\u062f \u0648 \u0627\u06af\u0631 \u06cc\u06a9 \u0622\u0628\u0633\u0647 \u067e\u0631 \u0627\u0632 \u0686\u0631\u06a9 \u0627\u0632 \u063a\u062f\u0647 \u0639\u0641\u0648\u0646\u06cc \u0627\u06cc\u062c\u0627\u062f \u0634\u0648\u062f\u060c \u0627\u06cc\u0646 \u0645\u06cc\u0632\u0627\u0646 \u0628\u0647 75 \u062f\u0631\u0635\u062f \u0645\u06cc \u0631\u0633\u062f. \u0686\u0631\u06a9 \u0628\u0627\u06cc\u062f \u0631\u0627\u0647\u06cc \u0628\u0631\u0627\u06cc \u062a\u062e\u0644\u06cc\u0647 \u0628\u0647 \u0628\u06cc\u0631\u0648\u0646 \u0628\u06cc\u0627\u0628\u062f \u0648 \u0627\u06cc\u0646 \u0634\u0631\u0648\u0639 \u062a\u0648\u0646\u0644 \u0632\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0641\u06cc\u0633\u062a\u0648\u0644 \u0631\u0627 \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<p style=\"text-align: justify;\">\u0646\u0627\u062d\u06cc\u0647 \u0645\u0642\u0639\u062f \u0633\u0631\u0634\u0627\u0631 \u0627\u0632 \u0628\u0627\u06a9\u062a\u0631\u06cc \u0627\u0633\u062a\u060c \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u062e\u0637\u0631 \u0639\u0641\u0648\u0646\u062a \u0645\u062c\u062f\u062f \u0632\u06cc\u0627\u062f \u0627\u0633\u062a. \u062f\u0631\u0645\u0627\u0646 \u0639\u0641\u0648\u0646\u062a \u0628\u0647 \u062a\u0646\u0647\u0627\u06cc\u06cc \u0641\u06cc\u0633\u062a\u0648\u0644 \u0645\u0642\u0639\u062f\u06cc \u0631\u0627 \u062f\u0631\u0645\u0627\u0646 \u0646\u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<p style=\"text-align: justify;\">\u0647\u0646\u06af\u0627\u0645\u06cc \u06a9\u0647 \u0622\u0628\u0633\u0647 \u0646\u0627\u062d\u06cc\u0647 \u0645\u0642\u0639\u062f \u0631\u0627 \u062a\u062d\u062a \u062a\u0627\u062b\u06cc\u0631 \u0642\u0631\u0627\u0631 \u0645\u06cc \u062f\u0647\u062f\u060c \u06cc\u06a9 \u062a\u0648\u0646\u0644 \u0628\u06cc\u0646 \u067e\u0648\u0633\u062a \u0628\u0627\u0633\u0646 \u0648 \u06a9\u0627\u0646\u0627\u0644 \u0645\u0642\u0639\u062f\u06cc \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc \u0634\u0648\u062f. \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u06a9\u0647 \u0641\u06cc\u0633\u062a\u0648\u0644 \u0645\u0642\u0639\u062f\u06cc \u0646\u0627\u0645\u06cc\u062f\u0647 \u0645\u06cc\u202f\u0634\u0648\u062f\u060c \u06cc\u06a9 \u0628\u06cc\u0645\u0627\u0631\u06cc \u062f\u0631\u062f\u0646\u0627\u06a9 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0635\u0648\u0631\u062a \u0639\u062f\u0645 \u062f\u0631\u0645\u0627\u0646\u060c \u062e\u0637\u0631 \u0639\u0648\u0627\u0631\u0636 \u0632\u06cc\u0627\u062f\u06cc \u0631\u0627 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0631\u062f.<\/p>\n<p style=\"text-align: justify;\">\u0639\u0644\u0627\u0626\u0645 \u0641\u06cc\u0633\u062a\u0648\u0644 \u0645\u0642\u0639\u062f\u06cc \u0634\u0627\u0645\u0644 \u062f\u0631\u062f \u0648 \u0627\u0644\u062a\u0647\u0627\u0628 \u062f\u0631 \u0646\u0627\u062d\u06cc\u0647 \u0645\u0642\u0639\u062f \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0642\u0631\u0645\u0632\u06cc \u0648 \u062e\u0627\u0631\u0634 \u0645\u0648\u0636\u0639\u06cc \u0627\u0633\u062a. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062a\u062e\u0644\u06cc\u0647 \u0686\u0631\u06a9 \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0639\u0641\u0648\u0646\u062a \u0632\u0645\u06cc\u0646\u0647 \u0627\u06cc \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0627 \u0627\u062d\u0633\u0627\u0633 \u0645\u062a\u0646\u0627\u0648\u0628 \u062a\u0628 \u0648 \u0644\u0631\u0632 \u0628\u0627\u0639\u062b \u062e\u0633\u062a\u06af\u06cc \u0634\u0645\u0627 \u0634\u0648\u062f.<br \/>\u0627\u06af\u0631 \u0628\u0627 \u0639\u0648\u0627\u0631\u0636 \u0641\u06cc\u0633\u062a\u0648\u0644 \u0645\u0642\u0639\u062f\u06cc \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc \u06a9\u0646\u06cc\u062f\u060c \u0627\u062d\u062a\u0645\u0627\u0644 \u0627\u06cc\u0646\u06a9\u0647 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u062e\u0648\u062f \u0628\u0647 \u062e\u0648\u062f \u0628\u0631\u0637\u0631\u0641 \u0634\u0648\u062f \u0628\u0633\u06cc\u0627\u0631 \u0636\u0639\u06cc\u0641 \u0627\u0633\u062a. \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0628\u0627 \u0634\u0631\u0648\u0639 \u0639\u0644\u0627\u0626\u0645\u060c \u0628\u0631\u0627\u06cc \u062a\u0634\u062e\u06cc\u0635 \u062f\u0642\u06cc\u0642 \u062a\u0648\u0633\u0637 \u06cc\u06a9 \u0645\u062a\u062e\u0635\u0635 \u062c\u0631\u0627\u062d \u0639\u0645\u0648\u0645\u06cc \u06cc\u0627 \u062f\u06a9\u062a\u0631 \u062c\u0631\u0627\u062d \u0641\u06cc\u0633\u062a\u0648\u0644 \u062f\u0631 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/clinicdarman.com\/\">\u06a9\u0644\u06cc\u0646\u06cc\u06a9 \u0644\u06cc\u0632\u0631 \u0641\u06cc\u0633\u062a\u0648\u0644<\/a> \u0645\u0639\u0627\u06cc\u0646\u0647 \u0648 \u0648\u06cc\u0632\u06cc\u062a \u0634\u0648\u06cc\u062f.<\/p>\n<p>\n\u0645\u0633\u0648\u0648\u0644\u06cc\u062a \u06a9\u0644\u06cc\u0647 \u0645\u062d\u062a\u0648\u0627\u06cc \u0633\u0627\u06cc\u062a \u0628\u0631 \u0639\u0647\u062f\u0647 \u0645\u0646\u0627\u0628\u0639 \u0627\u0635\u0644\u06cc \u0628\u0648\u062f\u0647 \u0648 \u0628\u0627\u0646\u06a9 \u0645\u0634\u0627\u063a\u0644 \u0627\u06cc\u0646\u0641\u0648\u062c\u0627\u0628 \u0647\u06cc\u0686 \u0645\u0633\u0648\u0648\u0644\u06cc\u062a\u06cc \u062f\u0631 \u0642\u0628\u0627\u0644 \u0645\u062d\u062a\u0648\u0627 \u0646\u062f\u0627\u0631\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u063a\u0644\u0628 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0641\u06cc\u0633\u062a\u0648\u0644\u060c \u0639\u0645\u0644 \u062c\u0631\u0627\u062d\u06cc \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u0627\u0633\u062a \u0632\u06cc\u0631\u0627 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0628\u0647 \u062e\u0648\u062f\u06cc \u062e\u0648\u062f \u0628\u0647\u0628\u0648\u062f \u0646\u0645\u06cc \u06cc\u0627\u0628\u062f. \u0686\u0646\u062f\u06cc\u0646 \u0631\u0648\u0634 \u062f\u0631\u0645\u0627\u0646 \u0645\u062e\u062a\u0644\u0641 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f. \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0628\u0633\u062a\u06af\u06cc \u0628\u0647 \u0645\u0648\u0642\u0639\u06cc\u062a \u0648 \u0634\u062f\u062a \u0641\u06cc\u0633\u062a\u0648\u0644 \u062f\u0627\u0631\u062f \u0648 \u0627\u06cc\u0646\u06a9\u0647 \u0622\u06cc\u0627 \u0627\u06cc\u0646 \u0641\u06cc\u0633\u062a\u0648\u0644 \u06cc\u06a9 \u06a9\u0627\u0646\u0627\u0644 \u0627\u0633\u062a \u06cc\u0627 \u062f\u0631 \u062c\u0647\u0627\u062a \u0645\u062e\u062a\u0644\u0641 \u0645\u0646\u0634\u0639\u0628 \u0645\u06cc \u0634\u0648\u062f. \u0627\u06cc\u0627 \u0645\u06cc\u0634\u0648\u062f \u0641\u06cc\u0633\u062a\u0648\u0644 \u0631\u0627 \u0639\u0645\u0644 \u0646\u06a9\u0631\u062f &hellip;<\/p>\n","protected":false},"author":2,"featured_media":39133,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69],"tags":[],"class_list":["post-39132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diet"],"_links":{"self":[{"href":"https:\/\/ijmarket.com\/blog\/wp-json\/wp\/v2\/posts\/39132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ijmarket.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ijmarket.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ijmarket.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ijmarket.com\/blog\/wp-json\/wp\/v2\/comments?post=39132"}],"version-history":[{"count":1,"href":"https:\/\/ijmarket.com\/blog\/wp-json\/wp\/v2\/posts\/39132\/revisions"}],"predecessor-version":[{"id":39134,"href":"https:\/\/ijmarket.com\/blog\/wp-json\/wp\/v2\/posts\/39132\/revisions\/39134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ijmarket.com\/blog\/wp-json\/wp\/v2\/media\/39133"}],"wp:attachment":[{"href":"https:\/\/ijmarket.com\/blog\/wp-json\/wp\/v2\/media?parent=39132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ijmarket.com\/blog\/wp-json\/wp\/v2\/categories?post=39132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ijmarket.com\/blog\/wp-json\/wp\/v2\/tags?post=39132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}